{"id":8,"count":1,"description":"","link":"https:\/\/fideamerica.net\/site\/tag\/femenino\/","name":"femenino","slug":"femenino","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/tags\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts?tags=8"},{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/ajde_events?tags=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}