{"id":144,"date":"2022-11-14T14:49:39","date_gmt":"2022-11-14T14:49:39","guid":{"rendered":"http:\/\/localhost\/fideamerica\/?p=144"},"modified":"2022-11-14T14:49:39","modified_gmt":"2022-11-14T14:49:39","slug":"campeonato-panamericano-de-ajedrez-amateur-mexico-2022","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/2022\/11\/14\/campeonato-panamericano-de-ajedrez-amateur-mexico-2022\/","title":{"rendered":"Campeonato Panamericano de Ajedrez Amateur \u201cM\u00e9xico 2022\u201d"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Del 27 de noviembre al 1 de diciembre en Ciudad de Mexico<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Podr\u00e1n participar todos los jugadores y jugadoras, avalados por su respectiva Federaci\u00f3n miembro de la Confederaci\u00f3n de Ajedrez para Am\u00e9rica.<br \/>En todos los casos, se deber\u00e1 contar con el aval escrito de la federaci\u00f3n de procedencia. <\/p>\n\n\n\n<p>El torneo se disputar\u00e1 en las categorias sub 2300, sub 2000 y sub 1700<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema de competencia.<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sistema Suizo 9 rondas, con el programa Swiss Manger.<\/li>\n\n\n\n<li>El sistema de competencia podr\u00e1 variar si el n\u00famero de participantes en alguno<br \/>de los grupos as\u00ed lo requiriera.<\/li>\n\n\n\n<li>El ritmo de juego ser\u00e1 de 90 minutos para toda la partida por jugador, con<br \/>incrementos de 30 segundos por movimientos.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Procedimiento de registro:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se debe enviar un correo electr\u00f3nico a sandrazamudio@fenamac.mx,<br \/>anexando:<\/li>\n\n\n\n<li>Nombre completo del participante.<\/li>\n\n\n\n<li>ID FIDE.<\/li>\n\n\n\n<li>Fecha de nacimiento.<\/li>\n\n\n\n<li>Categor\u00eda a la que se inscribe.<\/li>\n\n\n\n<li>Fotograf\u00eda tama\u00f1o infantil.<\/li>\n\n\n\n<li>Correo electr\u00f3nico.<\/li>\n\n\n\n<li>N\u00famero de WhatsApp.<\/li>\n\n\n\n<li>Aval escrito de su Federaci\u00f3n en PDF.<\/li>\n\n\n\n<li>Comprobante del dep\u00f3sito.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-ce1fed66-8bac-4510-951d-5bcde072296d\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Convocatoria-Panamericano-Amateur-Mexico-2022_221108_085550-1.pdf\">Convocatoria-Panamericano-Amateur-Mexico-2022_221108_085550<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Convocatoria-Panamericano-Amateur-Mexico-2022_221108_085550-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ce1fed66-8bac-4510-951d-5bcde072296d\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Del 27 de noviembre al 1 de diciembre en Ciudad de Mexico Podr\u00e1n participar todos los jugadores y jugadoras, avalados por su respectiva Federaci\u00f3n miembro<\/p>\n","protected":false},"author":1,"featured_media":147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-torneos"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/media\/147"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}