{"id":1062,"date":"2024-02-26T20:21:14","date_gmt":"2024-02-26T20:21:14","guid":{"rendered":"https:\/\/fideamerica.net\/site\/?p=1062"},"modified":"2024-02-26T20:21:14","modified_gmt":"2024-02-26T20:21:14","slug":"seminario-de-certificacion-de-arbitro-internacional","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/2024\/02\/26\/seminario-de-certificacion-de-arbitro-internacional\/","title":{"rendered":"Seminario de Certificaci\u00f3n de \u00c1rbitro Internacional"},"content":{"rendered":"\n<p>Link en ingles <a href=\"https:\/\/arbiters.fide.com\/news\/8989\">https:\/\/arbiters.fide.com\/news\/8989<\/a><\/p>\n\n\n\n<p>Estimados \u00e1rbitros de ajedrez y especialmente \u00e1rbitros de la FIDE:<\/p>\n\n\n\n<p>La Comisi\u00f3n de \u00c1rbitros de la FIDE ya anunci\u00f3 que nuestro objetivo es tener \u00e1rbitros bien preparados y educados.&nbsp;Entendemos que s\u00f3lo los \u00e1rbitros que se preparan para los eventos de ajedrez y conocen bien las regulaciones efectivas de la FIDE pueden actuar al m\u00e1s alto nivel.&nbsp;Queremos apoyar a los \u00e1rbitros y por eso nuestra decisi\u00f3n fue iniciar el Seminario Internacional de Certificaci\u00f3n de \u00c1rbitros (Seminarios IA) en 2024, no posponerlos para un a\u00f1o m\u00e1s.<\/p>\n\n\n\n<p>De acuerdo con el&nbsp;<a href=\"https:\/\/handbook.fide.com\/chapter\/B0602\" target=\"_blank\" rel=\"noreferrer noopener\">Reglamento de la FIDE para la formaci\u00f3n de \u00e1rbitros de ajedrez<\/a>&nbsp;, a partir del 1 de enero&nbsp;<sup>de<\/sup>&nbsp;&nbsp;2024, cada solicitud de \u00e1rbitro de IA requiere una norma del Seminario de IA.&nbsp;La duraci\u00f3n del Seminario IA ser\u00e1 de un m\u00ednimo de diecis\u00e9is (16) horas en al menos dos (2) d\u00edas.<\/p>\n\n\n\n<p>Por favor, no consideren esto como un obst\u00e1culo, t\u00f3menlo como un paso importante para alcanzar nuestro objetivo: ver \u00e1rbitros mejor preparados, que asuman la responsabilidad de su educaci\u00f3n.<\/p>\n\n\n\n<p>Los Seminarios IA no son el \u00fanico proyecto educativo de la comisi\u00f3n de \u00c1rbitros de la FIDE.&nbsp;Tambi\u00e9n trabajamos en otro proyecto: cursos de actualizaci\u00f3n. Este proyecto en l\u00ednea a su propio ritmo ser\u00e1 obligatorio para todos los \u00e1rbitros internacionales y de la FIDE.<\/p>\n\n\n\n<p>Pero volvamos a los Seminarios IA, existen claras diferencias entre los Seminarios FIDE y los Seminarios IA:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El contenido de los Seminarios IA difiere de los Seminarios FA, centr\u00e1ndose en las habilidades pr\u00e1cticas definidas en el Reglamento)<\/li>\n\n\n\n<li>Los seminarios de IA son para \u00e1rbitros de la FIDE (los seminarios de FA son para \u00e1rbitros nacionales)<\/li>\n\n\n\n<li>Los seminarios IA son impartidos por dos profesores (los seminarios FA los imparte un profesor)<\/li>\n\n\n\n<li>Los seminarios IA se eval\u00faan mediante una evaluaci\u00f3n de preparaci\u00f3n al final de los temas (los seminarios FA concluyen mediante un examen escrito)<\/li>\n\n\n\n<li>El Seminario IA es para un m\u00e1ximo de 25 participantes (el l\u00edmite de los Seminarios FA es de 20 participantes)<\/li>\n\n\n\n<li>El seminario IA es en ingl\u00e9s (los seminarios FA son en cualquier idioma de la FIDE)<\/li>\n<\/ol>\n\n\n\n<p><strong>El primer Seminario de IA en l\u00ednea se llevar\u00e1 a cabo del 15&nbsp;<sup>al<\/sup>&nbsp;&nbsp;16 de marzo&nbsp;<sup>de<\/sup>&nbsp;2024<\/strong><\/p>\n\n\n\n<p>15 de marzo: 14:00-18:15 CET y 18:45-23:00 CET<br \/>16 de marzo: 14:00-18:15 CET y 18:45-23:00 CET<\/p>\n\n\n\n<p><strong>El Segundo Seminario de IA en l\u00ednea se llevar\u00e1 a cabo del 22&nbsp;<sup>al<\/sup>&nbsp;&nbsp;23&nbsp;<sup>de<\/sup>&nbsp;marzo de 2024.<\/strong><\/p>\n\n\n\n<p>22 de marzo: 10:00-14:15 CET y 14:45-19:00 CET<br \/>23 de marzo: 10:00-14:15 CET y 14:45-19:00 CET<\/p>\n\n\n\n<p>Cuotas de inscripci\u00f3n al Seminario IA&nbsp;: 130 \u20ac<\/p>\n\n\n\n<p>Contacto e inscripci\u00f3n&nbsp;: Nebojsa Baralic, Secretario del ARB de la FIDE (secretary.arbiters@fide.com)<\/p>\n\n\n\n<p>El profesor principal de ambos seminarios es el IA Alex MacFarlane, profesor experimentado, l\u00edder del equipo educativo en ARB y autor de materiales para los seminarios certificados de IA.<\/p>\n\n\n\n<p>La organizaci\u00f3n del seminario continuar\u00e1 en los pr\u00f3ximos meses.<\/p>\n\n\n\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013\u2013<\/p>\n\n\n\n<p><em>Ivan Syrovy, presidente de la ARB<\/em><\/p>\n\n\n\n<p><em>Nebojsa Baralic, Secretario de la ARB<\/em><\/p>\n\n\n\n<p><em>Alex McFarlane, l\u00edder del equipo educativo de ARB<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Link en ingles https:\/\/arbiters.fide.com\/news\/8989 Estimados \u00e1rbitros de ajedrez y especialmente \u00e1rbitros de la FIDE: La Comisi\u00f3n de \u00c1rbitros de la FIDE ya anunci\u00f3 que nuestro<\/p>\n","protected":false},"author":1,"featured_media":1063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbitraje"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/media\/1063"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}