{"id":284,"date":"2022-11-17T20:06:14","date_gmt":"2022-11-17T20:06:14","guid":{"rendered":"https:\/\/fideamerica.net\/site\/?page_id=284"},"modified":"2022-11-17T20:06:14","modified_gmt":"2022-11-17T20:06:14","slug":"calendario-cca-2023","status":"publish","type":"page","link":"https:\/\/fideamerica.net\/site\/calendario-cca-2023\/","title":{"rendered":"Calendario CCA 2023"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2023\/09\/Calendario2023CCA-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Calendario2023CCA.\"><\/object><a id=\"wp-block-file--media-59a8b182-cd08-4851-99b4-e0c6837de8ce\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2023\/09\/Calendario2023CCA-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Calendario2023CCA<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2023\/09\/Calendario2023CCA-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-59a8b182-cd08-4851-99b4-e0c6837de8ce\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-284","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/pages\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/pages\/284\/revisions"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/wp-json\/wp\/v2\/media?parent=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}