{"id":223,"date":"2022-11-16T14:12:17","date_gmt":"2022-11-16T14:12:17","guid":{"rendered":"https:\/\/fideamerica.net\/site\/?p=223"},"modified":"2022-11-16T14:12:17","modified_gmt":"2022-11-16T14:12:17","slug":"campeonato-continental-femenino-de-ajedrez-de-las-americas-ecuador-2022","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/en\/2022\/11\/16\/campeonato-continental-femenino-de-ajedrez-de-las-americas-ecuador-2022\/","title":{"rendered":"Campeonato Continental Femenino de Ajedrez de las Americas \u00abEcuador 2022\u00bb"},"content":{"rendered":"<p>La Confederaci\u00f3n de Ajedrez de las Am\u00e9ricas (CCA), la Federaci\u00f3n Ecuatoriana de Ajedrez (FEDA), tienen el agrado de invitar a todas las Federaciones Nacionales de Ajedrez del Continente Americano, al Campeonato Continental Femenino de ajedrez de las Am\u00e9ricas 2022, que se celebrar\u00e1 del 5 al 10 de diciembre del 2022, en la ciudad de Cuenca, provincia del Azuay &#8211; Ecuador.<\/p>\n\n\n\n<p>El Campeonato Continental Femenino es organizado por la Federaci\u00f3n Ecuatoriana de Ajedrez \u2013 FEDA.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De los participantes<\/h3>\n\n\n\n<p><strong>Jugadoras oficiales:<\/strong> <\/p>\n\n\n\n<p>Estos deportistas tienen derecho al alojamiento y alimentaci\u00f3n completa a cargo de la organizaci\u00f3n, desde el domingo 4 de diciembre a las 14 horas hasta el domingo 11 de diciembre a las 14 horas:<br \/><br \/>&#8211; Una deportista designada por el presidente Continental<br \/>&#8211; Hasta 3 deportistas de la zona 2.1<br \/>&#8211; Una deportista de la zona 2.2<br \/>&#8211; Hasta 2 deportistas de cada una de las zonas 2.3, 2.4, y 2.5<br \/>&#8211; La Campeona Continental Femenina del a\u00f1o 2021.<br \/>&#8211; La Campeona Panamericana Junior<br \/>&#8211; Una deportista invitada por la Organizaci\u00f3n.<\/p>\n\n\n\n<p>Las deportistas oficiales ser\u00e1n hospedadas en habitaci\u00f3n doble. Su designaci\u00f3n tendr\u00e1 que<br \/>ser notificada a la organizaci\u00f3n por los presidentes de cada zona, a m\u00e1s tardar el 30 de<br \/>noviembre de 2022.<\/p>\n\n\n\n<p><strong>Jugadoras extraoficiales<\/strong>: <\/p>\n\n\n\n<p>El campeonato Continental femenino es un torneo abierto (sin requerimiento m\u00ednimo de ELO FIDE). Cada federaci\u00f3n Nacional podr\u00e1 inscribir las ajedrecistas que desee. Todas las participantes deber\u00e1n cubrir sus costos de inscripci\u00f3n, transporte y acreditaci\u00f3n. Cada una de las participantes deber\u00e1 tener el aval de su Federaci\u00f3n perteneciente a la Confederaci\u00f3n de Ajedrez para Am\u00e9rica, inscrita en la FIDE, salvo opini\u00f3n contraria del presidente de la CCA.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inscripciones.<\/h3>\n\n\n\n<p>Las deportistas oficiales deber\u00e1n ser inscritas por las Federaciones correspondientes antes de finalizar el d\u00eda 22 de noviembre de 2022, mediante correo enviado a federacionecuatorianadeajedrez@gmail.com. Luego de cumplido ese plazo todas las deportistas ser\u00e1n consideradas no oficiales.<br \/>Ninguna jugadora podr\u00e1 ser inscrita sin el visto bueno de su propia Federaci\u00f3n o si no pertenece a la regi\u00f3n correspondiente a este torneo.<br \/>Para que la inscripci\u00f3n de una atleta se considere completada, deber\u00e1 proveer la siguiente informaci\u00f3n: Nombres y apellidos completos, documento de identidad (n\u00famero de pasaporte), FIDE ID, fotograf\u00eda actual tama\u00f1o pasaporte, fecha completa de nacimiento (en el formato mm-dd-aaaa), titulo FIDE. E s t a<br \/>informaci\u00f3n deber\u00e1 ser corroborada al arribo presentando el pasaporte o documento de identidad para efectos de verificaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Invitaci\u00f3n y bases completas del evento.<\/h3>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-5aa91938-47cb-4176-9489-bb2a194708dd\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Bases-Continental-Femenino-2022-Ecuador-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Bases-Continental-Femenino-2022-Ecuador<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Bases-Continental-Femenino-2022-Ecuador-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-5aa91938-47cb-4176-9489-bb2a194708dd\">Descarga<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-63c3bcfe-0790-4f86-8dce-8792a607b6c4\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/12\/Womens-Continental-Bases-2022-Ecuador-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Womens-Continental-Bases-2022-Ecuador<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/12\/Womens-Continental-Bases-2022-Ecuador-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-63c3bcfe-0790-4f86-8dce-8792a607b6c4\">Descarga<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>La Confederaci\u00f3n de Ajedrez de las Am\u00e9ricas (CCA), la Federaci\u00f3n Ecuatoriana de Ajedrez (FEDA), tienen el agrado de invitar a todas las Federaciones Nacionales de<\/p>","protected":false},"author":1,"featured_media":225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2,3],"tags":[7,8],"class_list":["post-223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-novedades","category-torneos","tag-continental","tag-femenino"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media\/225"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}