{"id":1709,"date":"2024-11-25T23:27:31","date_gmt":"2024-11-25T23:27:31","guid":{"rendered":"https:\/\/fideamerica.net\/site\/?p=1709"},"modified":"2024-11-25T23:27:31","modified_gmt":"2024-11-25T23:27:31","slug":"finaliza-la-segunda-edicion-del-programa-jovenes-talentos","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/en\/2024\/11\/25\/finaliza-la-segunda-edicion-del-programa-jovenes-talentos\/","title":{"rendered":"Finaliza la segunda edici\u00f3n del programa J\u00f3venes Talentos"},"content":{"rendered":"<p>La Comisi\u00f3n de Entrenadores de FIDE Am\u00e9rica celebr\u00f3 el cierre de la segunda edici\u00f3n del programa <em>J\u00f3venes Talentos<\/em>, que este a\u00f1o brind\u00f3 entrenamiento gratuito a casi 100 promesas del ajedrez de Latinoam\u00e9rica, seleccionadas por su destacado rendimiento en cada pa\u00eds.<\/p>\n\n\n\n<p>El programa cont\u00f3 con la participaci\u00f3n de alumnos provenientes de Argentina, Bolivia, Brasil, Chile, Colombia, Costa Rica, Cuba, Ecuador, El Salvador, Guatemala, M\u00e9xico, Nicaragua, Panam\u00e1, Paraguay, Per\u00fa y Uruguay.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2024\/11\/4-1-819x1024.png\" alt=\"\" class=\"wp-image-1710\" style=\"width:461px;height:auto\"\/><\/figure>\n\n\n\n<p>El equipo de profesores estuvo conformado por entrenadores de renombre internacional:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GM Rafael Leitao<\/strong> (Brasil)<\/li>\n\n\n\n<li><strong>GM David Arenas<\/strong> (Colombia)<\/li>\n\n\n\n<li><strong>WGM Claudia Amura<\/strong> (Argentina)<\/li>\n\n\n\n<li><strong>WIM Gabriela Vargas<\/strong> (Paraguay)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2024\/11\/jovenes-talentos-2024-1080-x-1350-px-1-819x1024.png\" alt=\"\" class=\"wp-image-1711\" style=\"width:509px;height:auto\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Como parte de las actividades de cierre, se organiz\u00f3 un emocionante torneo blitz que reuni\u00f3 a alumnos y profesores, creando un ambiente \u00fanico de camarader\u00eda y competencia. Este evento fue una excelente forma de poner a prueba las habilidades adquiridas durante el a\u00f1o y de fortalecer los lazos entre los participantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2024\/11\/2-1-819x1024.png\" alt=\"\" class=\"wp-image-1712\" style=\"width:464px;height:auto\"\/><\/figure>\n\n\n\n<p>Este esfuerzo conjunto reafirma el compromiso de la Comisi\u00f3n de Entrenadores de FIDE Am\u00e9rica con el desarrollo del talento joven en la regi\u00f3n. Luego de un a\u00f1o de intenso trabajo y aprendizaje, esperamos poder repetir esta experiencia en 2025, continuando con nuestra misi\u00f3n de formar a las grandes promesas y futuros protagonistas del ajedrez de Latinoam\u00e9rica.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Entrenadores de FIDE Am\u00e9rica celebr\u00f3 el cierre de la segunda edici\u00f3n del programa J\u00f3venes Talentos, que este a\u00f1o brind\u00f3 entrenamiento gratuito a casi 100 promesas del ajedrez de Latinoam\u00e9rica, seleccionadas por su destacado rendimiento en cada pa\u00eds.<\/p>","protected":false},"author":1,"featured_media":1713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tca"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/comments?post=1709"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/1709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media\/1713"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media?parent=1709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/categories?post=1709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/tags?post=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}