{"id":149,"date":"2022-11-14T15:25:08","date_gmt":"2022-11-14T15:25:08","guid":{"rendered":"http:\/\/localhost\/fideamerica\/?p=149"},"modified":"2022-11-14T15:25:08","modified_gmt":"2022-11-14T15:25:08","slug":"xviii-festival-sudamericano-de-la-juventud-paraguay-2022","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/en\/2022\/11\/14\/xviii-festival-sudamericano-de-la-juventud-paraguay-2022\/","title":{"rendered":"XVIII Festival Sudamericano de la Juventud Paraguay 2022"},"content":{"rendered":"<figure class=\"wp-block-table\"><table><tbody><tr><td>La Confederaci\u00f3n de Ajedrez de las Am\u00e9ricas (CCA) y la Federaci\u00f3n Paraguaya de Ajedrez<br \/>(FEPARAJ) tienen el agrado de invitar a todas las Federaciones Nacionales de Ajedrez de<br \/>Sudam\u00e9rica al XVIII Festival Sudamericano de la Juventud 2022, que se celebrar\u00e1 desde el 30 de<br \/>noviembre al 6 de Diciembre de 2022.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Las Federaciones Nacionales de ARGENTINA, BOLIVIA, BRASIL, COLOMBIA, CHILE, ECUADOR,<br \/>PARAGUAY, PER\u00da, URUGUAY y VENEZUELA podr\u00e1n inscribir deportistas en el evento de acuerdo a<br \/>la siguiente designaci\u00f3n:<\/p>\n\n\n\n<p>Los eventos se distribuir\u00e1n en dos ramas: Absoluta y Femenina siendo las categor\u00edas las siguientes:<br \/>&#8211; Sub 18:Nacidos desde el 1\u00b0 de Enero de 2004 a la fecha<br \/>&#8211; Sub 16:Nacidos desde el 1\u00b0 de Enero de 2006 a la fecha<br \/>&#8211; Sub 14:Nacidos desde el 1\u00b0 de Enero de 2008 a la fecha<br \/>&#8211; Sub 12:Nacidos desde el 1\u00b0 de Enero de 2010 a la fecha<br \/>&#8211; Sub 10:Nacidos desde el 1\u00b0 de Enero de 2012 a la fecha<br \/>&#8211; Sub 08:Nacidos desde el 1\u00b0 de Enero de 2014 a la fecha<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Disposiciones generales.<\/h3>\n\n\n\n<p>Se disputar\u00e1n en forma simult\u00e1nea 6 Torneos Absolutos, y 6 Torneos Femeninos<br \/>correspondientes a las categor\u00edas: Sub-8, Sub-10, Sub-12, Sub-14, Sub-16 y Sub-18. Todos los<br \/>torneos se jugar\u00e1n preferentemente por sistema Suizo a 9 rondas salvo aquellos en que el n\u00famero<br \/>de participantes sea menor de 8, en este caso el torneo no se celebrar\u00e1 y los jugadores inscriptos<br \/>participar\u00e1n de otro torneo con jugadores de la misma categor\u00eda. Cuando el total de participantes<br \/>de la misma categor\u00eda es menor a 9, entonces los jugadores se unir\u00e1n a la siguiente categor\u00eda de<br \/>edad superior. La premiaci\u00f3n ser\u00e1 por separado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Proceso deinscripci\u00f3n al evento.<\/h3>\n\n\n\n<p>Cada Federaci\u00f3n deber\u00e1 informar a la Organizaci\u00f3n mediante correo electr\u00f3nico el detalle de los<br \/>participantes en el evento y su inscripci\u00f3n (Jugadores Oficiales, Jugadores Extras, Jefe de<br \/>Delegaci\u00f3n y Acompa\u00f1antes) indicando la siguiente informaci\u00f3n.<br \/><br \/>\u2013 Nombre Completo del participante.<br \/>\u2013 FIDE ID (Si no posee deber\u00e1 generarla el administrador de Rating local)<br \/>\u2013 N\u00famero de C\u00e9dula o DNI<br \/>\u2013 Fecha de Nacimiento.<br \/>\u2013 Categor\u00eda a Participar.<br \/>&#8211; Fotograf\u00eda del Jugador.<br \/>\u2013 Comprobante de Pago de Inscripci\u00f3n, Acreditaci\u00f3n, Transporte y Estad\u00eda (Seg\u00fan corresponda).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Invitaci\u00f3n y bases del evento ara descargar.<\/h3>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-267fa53d-2ae5-48b7-a8ce-a8ea71bd50e8\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Invitacion_Festival_Sudamericano_Paraguay_2022-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Invitacion_Festival_Sudamericano_Paraguay_2022<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Invitacion_Festival_Sudamericano_Paraguay_2022-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-267fa53d-2ae5-48b7-a8ce-a8ea71bd50e8\">Descarga<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>La Confederaci\u00f3n de Ajedrez de las Am\u00e9ricas (CCA) y la Federaci\u00f3n Paraguaya de Ajedrez(FEPARAJ) tienen el agrado de invitar a todas las Federaciones Nacionales de<\/p>","protected":false},"author":1,"featured_media":152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-torneos"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media\/152"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}