{"id":132,"date":"2022-11-10T01:50:27","date_gmt":"2022-11-10T01:50:27","guid":{"rendered":"http:\/\/localhost\/fideamerica\/?p=132"},"modified":"2022-11-10T01:50:27","modified_gmt":"2022-11-10T01:50:27","slug":"xvii-festival-de-ajedrez-de-la-juventud-de-centroamerica-y-el-caribe-2022","status":"publish","type":"post","link":"https:\/\/fideamerica.net\/site\/en\/2022\/11\/10\/xvii-festival-de-ajedrez-de-la-juventud-de-centroamerica-y-el-caribe-2022\/","title":{"rendered":"XVII Festival de Ajedrez de la Juventud de Centroamerica y el Caribe 2022."},"content":{"rendered":"<figure class=\"wp-block-table\"><table><tbody><tr><td>Tegucigalpa, Honduras. Del 19 al 25 de Noviembre de 2022.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-left\">La Federaci\u00f3n Nacional de Ajedrez de Honduras (FENAH) y la Confederaci\u00f3n de Ajedrez de las<br \/>Am\u00e9ricas (CCA por sus siglas en ingl\u00e9s), tienen el agrado de invitar a todas las Federaciones de<br \/>Centroam\u00e9rica y el Caribe, al XVIII Festival de Ajedrez Centroamericano y del Caribe de la<br \/>Juventud, que se celebrar\u00e1 en la ciudad de Tegucigalpa, Honduras del 19 al 25 de noviembre de<br \/>2022, en el Florencia Plaza Hotel, ubicado en una de las mejores zonas de la ciudad, muy cerca de<br \/>los principales centros comerciales y financieros, restaurantes y las principales atracciones tur\u00edsticas<br \/>de la ciudad.<\/p>\n\n\n\n<p>Se jugar\u00e1n doce (12) Campeonatos en Absoluto y Femenino en las categor\u00edas: Sub 18, Sub 16, Sub<br \/>14, Sub 12, Sub 10 y Sub 8. Si en una o m\u00e1s categor\u00edas hay participantes insuficientes, la<br \/>organizaci\u00f3n puede unir dos o m\u00e1s de ellas para cumplir con el pareo de los jugadores.<\/p>\n\n\n\n<p>Puede ver toda la informaci\u00f3n del evento y descargar las bases en el siguiente enlace.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-774a8d52-96b2-44f9-9852-039240fc0b40\" href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Bases-Festival-CA-y-del-Caribe-de-la-Juventud-Honduras-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Bases-Festival-CA-y-del-Caribe-de-la-Juventud-Honduras<\/a><a href=\"https:\/\/fideamerica.net\/site\/wp-content\/uploads\/2022\/11\/Bases-Festival-CA-y-del-Caribe-de-la-Juventud-Honduras-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-774a8d52-96b2-44f9-9852-039240fc0b40\">Descarga<\/a><\/div>\n\n\n\n<p> <\/p>","protected":false},"excerpt":{"rendered":"<p>Tegucigalpa, Honduras. Del 19 al 25 de Noviembre de 2022. La Federaci\u00f3n Nacional de Ajedrez de Honduras (FENAH) y la Confederaci\u00f3n de Ajedrez de lasAm\u00e9ricas<\/p>","protected":false},"author":1,"featured_media":136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,3],"tags":[],"class_list":["post-132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-torneos"],"_links":{"self":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":0,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media\/136"}],"wp:attachment":[{"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fideamerica.net\/site\/en\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}